{"id":38,"date":"2008-06-06T00:00:00","date_gmt":"2008-06-06T00:00:00","guid":{"rendered":"http:\/\/blog.professionearchitetto.it\/FarEast\/2008\/06\/06\/yes-ui-chen(d)\/"},"modified":"2008-06-06T00:00:00","modified_gmt":"2008-06-06T00:00:00","slug":"yes-ui-chend","status":"publish","type":"post","link":"https:\/\/blog.professionearchitetto.it\/fareast\/2008\/06\/06\/yes-ui-chend\/","title":{"rendered":"yes, ui chen(d)"},"content":{"rendered":"<p>Solito post al volo mentre la ronda e&#8217; distratta.<\/p>\n<p>(In realta&#8217; qui mi lasciano molta liberta&#8217;, ma e&#8217; meglio non tirare troppo la corda).<\/p>\n<\/p>\n<p>Grazie innanzituto a quelli e che hanno lasciato un messaggio.<\/p>\n<p>Federico Grazie del tuo caloroso benvenuto. Chissa&#8217; quante volte ci saremo incrociati nei corridoi di via Micheli, testa bassa e sguardo spento <img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/blog.professionearchitetto.it\/wp-content\/uploads\/smileys\/sorriso.gif\" border=\"0\" alt=\"sorriso\" width=\"19\" height=\"19\" \/><\/p>\n<p>A chi mi chiede info sul lavoro i Cina. Boh, non sono un esperto ma un paio di link li ho, magari li posto appena possibile.<\/p>\n<p>A chi dice &#8220;si va beh, ma non diamo l&#8217;idea di essere poco professionali&#8221; dico che quello che ho scritto non e&#8217; poi cosi&#8217; distante dalla realta&#8217;&#8230;Faccio outing: ebene si&#8217;, sono un cialtrone<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/blog.professionearchitetto.it\/wp-content\/uploads\/smileys\/boccaperta.gif\" border=\"0\" alt=\"sorrisone\" width=\"19\" height=\"19\" \/><\/p>\n<p>Pero&#8217; ho tanta voglia di imparare e il bisogno di mettermi in gioco, e questo spero basti. <\/p>\n<p>Vorrei dare anche un consiglio a Burton, che da un anno vuole andare a Shanghai. Parti, fallo subito. E&#8217; la scelta giusta fatta al momento giusto. Qui tuto e&#8217; cosi&#8217; veloce che non ci si puo&#8217; permettere di essere indecisi.<\/p>\n<p>Vai, tasta il terreno che il prossimo anno vengo anch&#8217;io da quelle aprti e avro&#8217; bisogno di consigli&#8230;;)<\/p>\n<\/p>\n<p>Veniamo all&#8217;argomento del post:<\/p>\n<p>Dopo due mesi di non-saluti e di sguardi ironici, pochi minuti fa ho ricevuto questo biglietto:<\/p>\n<p><em>This weekend is Hong Kong very unique festival, &#8220;Dragon Boat Festival&#8221;, so we&#8217;ll have a long weekend.<\/em><\/p>\n<p><em>You can check on the following website for the special event in the city. Enjoy!<\/em><\/p>\n<p>Che c&#8217;e&#8217; di strano? TUTTO.<\/p>\n<p>Qui quando hai a che fare con le persone non puoi dare nulla per scontato. Per dirne una, ll mese scorso nessuno mi aveva avvisato della festa nazionale del &#8220;compleanno di Buddha&#8221;. Risultato: ero venuto in studio tutto bellino, con la mia faccia da lavoro, quella da bravo ragazzo che ha voglia di far progredire La repubblica Popolare di Cina e avevo trovato tuto buio (non che mi sia turbato piu&#8217; di tanto per carita&#8217;, due minuti dopodopo ero gia&#8217; in giro alla ricerca di gingilli elettronici).<\/p>\n<p>No, no e&#8217; facile lavorare n queste condizioni, ma piccole cose come questa ti fanno capire che anche la loro testardaggine e chiusura (lo dico con simpatia, visto che anche io faccio parte di un popolo testardo e chiuso) si puo&#8217; scalfire.<\/p>\n<p>Non &#8220;alla occidentale&#8221;come ho visto fare da troppe persone, con grandi pacche sulle spalle (poco gradite da queste parti) e forzature, ma come piace a loro: con umilta&#8217; e rispetto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>quando meno te lo aspetti&#8230; <a href=\"https:\/\/blog.professionearchitetto.it\/fareast\/2008\/06\/06\/yes-ui-chend\/\">[continua]<\/a><\/p>\n","protected":false},"author":23,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-38","post","type-post","status-publish","format-standard","hentry","category-senza-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>yes, ui chen(d) - Far East<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.professionearchitetto.it\/fareast\/2008\/06\/06\/yes-ui-chend\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"yes, ui chen(d) - Far East\" \/>\n<meta property=\"og:description\" content=\"quando meno te lo aspetti... [continua]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.professionearchitetto.it\/fareast\/2008\/06\/06\/yes-ui-chend\/\" \/>\n<meta property=\"og:site_name\" content=\"Far East\" \/>\n<meta property=\"article:published_time\" content=\"2008-06-06T00:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/blog.professionearchitetto.it\/wp-content\/uploads\/smileys\/sorriso.gif\" \/>\n<meta name=\"author\" content=\"holden\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"holden\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blog.professionearchitetto.it\/fareast\/2008\/06\/06\/yes-ui-chend\/\",\"url\":\"https:\/\/blog.professionearchitetto.it\/fareast\/2008\/06\/06\/yes-ui-chend\/\",\"name\":\"yes, ui chen(d) - Far East\",\"isPartOf\":{\"@id\":\"https:\/\/blog.professionearchitetto.it\/fareast\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/blog.professionearchitetto.it\/fareast\/2008\/06\/06\/yes-ui-chend\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/blog.professionearchitetto.it\/fareast\/2008\/06\/06\/yes-ui-chend\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/blog.professionearchitetto.it\/wp-content\/uploads\/smileys\/sorriso.gif\",\"datePublished\":\"2008-06-06T00:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/blog.professionearchitetto.it\/fareast\/#\/schema\/person\/28e53cb40831ffcb87b676ebb3315eac\"},\"breadcrumb\":{\"@id\":\"https:\/\/blog.professionearchitetto.it\/fareast\/2008\/06\/06\/yes-ui-chend\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blog.professionearchitetto.it\/fareast\/2008\/06\/06\/yes-ui-chend\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/blog.professionearchitetto.it\/fareast\/2008\/06\/06\/yes-ui-chend\/#primaryimage\",\"url\":\"http:\/\/blog.professionearchitetto.it\/wp-content\/uploads\/smileys\/sorriso.gif\",\"contentUrl\":\"http:\/\/blog.professionearchitetto.it\/wp-content\/uploads\/smileys\/sorriso.gif\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.professionearchitetto.it\/fareast\/2008\/06\/06\/yes-ui-chend\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blog.professionearchitetto.it\/fareast\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"yes, ui chen(d)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.professionearchitetto.it\/fareast\/#website\",\"url\":\"https:\/\/blog.professionearchitetto.it\/fareast\/\",\"name\":\"Far East\",\"description\":\"i blog di professionearchitetto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.professionearchitetto.it\/fareast\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/blog.professionearchitetto.it\/fareast\/#\/schema\/person\/28e53cb40831ffcb87b676ebb3315eac\",\"name\":\"holden\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/blog.professionearchitetto.it\/fareast\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a83fad3bf05b23a2bc883826550be60b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a83fad3bf05b23a2bc883826550be60b?s=96&d=mm&r=g\",\"caption\":\"holden\"},\"url\":\"https:\/\/blog.professionearchitetto.it\/fareast\/author\/holden\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"yes, ui chen(d) - Far East","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.professionearchitetto.it\/fareast\/2008\/06\/06\/yes-ui-chend\/","og_locale":"it_IT","og_type":"article","og_title":"yes, ui chen(d) - Far East","og_description":"quando meno te lo aspetti... [continua]","og_url":"https:\/\/blog.professionearchitetto.it\/fareast\/2008\/06\/06\/yes-ui-chend\/","og_site_name":"Far East","article_published_time":"2008-06-06T00:00:00+00:00","og_image":[{"url":"http:\/\/blog.professionearchitetto.it\/wp-content\/uploads\/smileys\/sorriso.gif","type":"","width":"","height":""}],"author":"holden","twitter_misc":{"Scritto da":"holden","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blog.professionearchitetto.it\/fareast\/2008\/06\/06\/yes-ui-chend\/","url":"https:\/\/blog.professionearchitetto.it\/fareast\/2008\/06\/06\/yes-ui-chend\/","name":"yes, ui chen(d) - Far East","isPartOf":{"@id":"https:\/\/blog.professionearchitetto.it\/fareast\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.professionearchitetto.it\/fareast\/2008\/06\/06\/yes-ui-chend\/#primaryimage"},"image":{"@id":"https:\/\/blog.professionearchitetto.it\/fareast\/2008\/06\/06\/yes-ui-chend\/#primaryimage"},"thumbnailUrl":"http:\/\/blog.professionearchitetto.it\/wp-content\/uploads\/smileys\/sorriso.gif","datePublished":"2008-06-06T00:00:00+00:00","author":{"@id":"https:\/\/blog.professionearchitetto.it\/fareast\/#\/schema\/person\/28e53cb40831ffcb87b676ebb3315eac"},"breadcrumb":{"@id":"https:\/\/blog.professionearchitetto.it\/fareast\/2008\/06\/06\/yes-ui-chend\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.professionearchitetto.it\/fareast\/2008\/06\/06\/yes-ui-chend\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/blog.professionearchitetto.it\/fareast\/2008\/06\/06\/yes-ui-chend\/#primaryimage","url":"http:\/\/blog.professionearchitetto.it\/wp-content\/uploads\/smileys\/sorriso.gif","contentUrl":"http:\/\/blog.professionearchitetto.it\/wp-content\/uploads\/smileys\/sorriso.gif"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.professionearchitetto.it\/fareast\/2008\/06\/06\/yes-ui-chend\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.professionearchitetto.it\/fareast\/"},{"@type":"ListItem","position":2,"name":"yes, ui chen(d)"}]},{"@type":"WebSite","@id":"https:\/\/blog.professionearchitetto.it\/fareast\/#website","url":"https:\/\/blog.professionearchitetto.it\/fareast\/","name":"Far East","description":"i blog di professionearchitetto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.professionearchitetto.it\/fareast\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/blog.professionearchitetto.it\/fareast\/#\/schema\/person\/28e53cb40831ffcb87b676ebb3315eac","name":"holden","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/blog.professionearchitetto.it\/fareast\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a83fad3bf05b23a2bc883826550be60b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a83fad3bf05b23a2bc883826550be60b?s=96&d=mm&r=g","caption":"holden"},"url":"https:\/\/blog.professionearchitetto.it\/fareast\/author\/holden\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.professionearchitetto.it\/fareast\/wp-json\/wp\/v2\/posts\/38","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.professionearchitetto.it\/fareast\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.professionearchitetto.it\/fareast\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.professionearchitetto.it\/fareast\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.professionearchitetto.it\/fareast\/wp-json\/wp\/v2\/comments?post=38"}],"version-history":[{"count":0,"href":"https:\/\/blog.professionearchitetto.it\/fareast\/wp-json\/wp\/v2\/posts\/38\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.professionearchitetto.it\/fareast\/wp-json\/wp\/v2\/media?parent=38"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.professionearchitetto.it\/fareast\/wp-json\/wp\/v2\/categories?post=38"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.professionearchitetto.it\/fareast\/wp-json\/wp\/v2\/tags?post=38"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}