{"id":2425,"date":"2012-03-03T16:21:00","date_gmt":"2012-03-03T15:21:00","guid":{"rendered":"http:\/\/blog.professionearchitetto.it\/giordanaquerceto\/?p=2425"},"modified":"2012-03-03T16:38:59","modified_gmt":"2012-03-03T15:38:59","slug":"bye-bye-singapore","status":"publish","type":"post","link":"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/2012\/03\/03\/bye-bye-singapore\/","title":{"rendered":"Bye Bye Singapore"},"content":{"rendered":"<p>Parlare di Singapore non toccherebbe a me, ma bensi al mio amato vicino di blog. Comunque a parte il pochissimo tempo che ho per scrivere questo post, devo dire che Singa e&#8217; una citta&#8217; strepitosa, formalmente commerciale per i miei gusti, ma ugualmente vivace e bella. Ieri sera siamo andati nella nuovissima zona di Marina Bay dove a parte tanti altri architetti e anche tanti\u00a0 dollari si sono spesi, consumati e sprecati, e tra migliaia di metri quadrati di superfici specchiate, vetrate, lucide, metalliche , ondulate e zig-zagate, si erge elegantissimo anche\u00a0 L&#8217; Elix Bridge. Una delle opere del gruppo di architetti australiano Cox, di cui parlo nel mio libro! Spettacolare tutta la zona illuminata di sera. Di giorno, sara che il tempo era uggioso, ma non ho notato sulla pelle la stessa sensazione magica della sera prima. Stasera siamo andati a cena per Daniel in un ristorante per babys, fantastico. L &#8216; avevo scovato per caso in internet da casa ad Amburgo. Colori , giochi, libri, sedioloni, bavette, cucchiaini colorati, tutto a misura di bambino.\u00a0 Mentre per noi siamo andati a cenare in una delle piu famose food court della citta a mangiare gamberi alla griglia, satay\u00a0e a bere tanta Tiger bier!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Parlare di Singapore non toccherebbe a me, ma bensi al mio amato vicino di blog. Comunque a parte il pochissimo tempo che ho per scrivere questo post, devo dire che Singa e&#8217; una citta&#8217; strepitosa, formalmente commerciale per i miei &hellip; <a href=\"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/2012\/03\/03\/bye-bye-singapore\/\">[continua]<\/a><\/p>\n","protected":false},"author":9,"featured_media":2431,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2425","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-senza-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bye Bye Singapore - Giordana, next stop: Hamburg<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/2012\/03\/03\/bye-bye-singapore\/\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"giordana querceto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/2012\/03\/03\/bye-bye-singapore\/\",\"url\":\"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/2012\/03\/03\/bye-bye-singapore\/\",\"name\":\"Bye Bye Singapore - Giordana, next stop: Hamburg\",\"isPartOf\":{\"@id\":\"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/2012\/03\/03\/bye-bye-singapore\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/2012\/03\/03\/bye-bye-singapore\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/files\/2012\/03\/Helix-Bridge-Singapore.jpg\",\"datePublished\":\"2012-03-03T15:21:00+00:00\",\"dateModified\":\"2012-03-03T15:38:59+00:00\",\"author\":{\"@id\":\"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/#\/schema\/person\/cb6939d8e4e71e17933f603c870f8493\"},\"breadcrumb\":{\"@id\":\"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/2012\/03\/03\/bye-bye-singapore\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/2012\/03\/03\/bye-bye-singapore\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/2012\/03\/03\/bye-bye-singapore\/#primaryimage\",\"url\":\"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/files\/2012\/03\/Helix-Bridge-Singapore.jpg\",\"contentUrl\":\"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/files\/2012\/03\/Helix-Bridge-Singapore.jpg\",\"width\":\"900\",\"height\":\"434\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/2012\/03\/03\/bye-bye-singapore\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bye Bye Singapore\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/#website\",\"url\":\"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/\",\"name\":\"Giordana, next stop: Hamburg\",\"description\":\"i blog di professionearchitetto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/#\/schema\/person\/cb6939d8e4e71e17933f603c870f8493\",\"name\":\"giordana querceto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/68ec2d79fc4da5052e0a4a02ebefe70f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/68ec2d79fc4da5052e0a4a02ebefe70f?s=96&d=mm&r=g\",\"caption\":\"giordana querceto\"},\"url\":\"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/author\/giordana-querceto\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bye Bye Singapore - Giordana, next stop: Hamburg","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/2012\/03\/03\/bye-bye-singapore\/","twitter_misc":{"Scritto da":"giordana querceto","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/2012\/03\/03\/bye-bye-singapore\/","url":"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/2012\/03\/03\/bye-bye-singapore\/","name":"Bye Bye Singapore - Giordana, next stop: Hamburg","isPartOf":{"@id":"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/2012\/03\/03\/bye-bye-singapore\/#primaryimage"},"image":{"@id":"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/2012\/03\/03\/bye-bye-singapore\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/files\/2012\/03\/Helix-Bridge-Singapore.jpg","datePublished":"2012-03-03T15:21:00+00:00","dateModified":"2012-03-03T15:38:59+00:00","author":{"@id":"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/#\/schema\/person\/cb6939d8e4e71e17933f603c870f8493"},"breadcrumb":{"@id":"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/2012\/03\/03\/bye-bye-singapore\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/2012\/03\/03\/bye-bye-singapore\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/2012\/03\/03\/bye-bye-singapore\/#primaryimage","url":"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/files\/2012\/03\/Helix-Bridge-Singapore.jpg","contentUrl":"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/files\/2012\/03\/Helix-Bridge-Singapore.jpg","width":"900","height":"434"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/2012\/03\/03\/bye-bye-singapore\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/"},{"@type":"ListItem","position":2,"name":"Bye Bye Singapore"}]},{"@type":"WebSite","@id":"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/#website","url":"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/","name":"Giordana, next stop: Hamburg","description":"i blog di professionearchitetto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/#\/schema\/person\/cb6939d8e4e71e17933f603c870f8493","name":"giordana querceto","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/68ec2d79fc4da5052e0a4a02ebefe70f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/68ec2d79fc4da5052e0a4a02ebefe70f?s=96&d=mm&r=g","caption":"giordana querceto"},"url":"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/author\/giordana-querceto\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/wp-json\/wp\/v2\/posts\/2425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/wp-json\/wp\/v2\/comments?post=2425"}],"version-history":[{"count":8,"href":"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/wp-json\/wp\/v2\/posts\/2425\/revisions"}],"predecessor-version":[{"id":2434,"href":"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/wp-json\/wp\/v2\/posts\/2425\/revisions\/2434"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/wp-json\/wp\/v2\/media\/2431"}],"wp:attachment":[{"href":"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/wp-json\/wp\/v2\/media?parent=2425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/wp-json\/wp\/v2\/categories?post=2425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.professionearchitetto.it\/giordanaquerceto\/wp-json\/wp\/v2\/tags?post=2425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}