{"id":47,"date":"2009-03-03T00:00:00","date_gmt":"2009-03-03T00:00:00","guid":{"rendered":"http:\/\/blog.professionearchitetto.it\/recibosverdes\/2009\/03\/03\/Non-mi-resta-che\/"},"modified":"2009-03-03T00:00:00","modified_gmt":"2009-03-03T00:00:00","slug":"non-mi-resta-che","status":"publish","type":"post","link":"https:\/\/blog.professionearchitetto.it\/recibosverdes\/2009\/03\/03\/non-mi-resta-che\/","title":{"rendered":"Non mi resta che"},"content":{"rendered":"<p><strong>&lt;&gt;<\/strong> <\/p>\n<p>Forse era meglio essere architetto negli anni &#8217;30, &#8217;40 e &#8217;60, quando, e ribadisco il &#8220;forse&#8221;, essere architetto voleva ancora significare qualcosa. Poi vi dico una cosa: se durante quelle tre decadi fossi stato in Portogallo, ma sai che pacchia&#8230;! Stava nascendo l&#8217;astro di <em>Siza<\/em>, ma lavoro ce n&#8217;era. Perch\u00e9 erano gli architetti che mancavano e di architetti si aveva bisogno. Anche nella seconda met\u00e0 degli anni &#8217;70, finita la dittatura. Niente Koolhaas, niente Gehry, niente architettura-champagne, ma tanto lavoro per tutti.<br \/>Lasciatemi crogiolare nel le mie teorie,,,, sono completamente sfiduciato da quando ho preso atto di quello che sta avvenendo sul globo terrestre a nostro discapito. Una realt\u00e0 probabilmente comune a molti paesi, ma io in questo momento posso fare un affresco solo della situazione <em>portuense<\/em>. E dunque succede che, a meno che uno non debba costruirsi una casa sulla propria fettina di terreno, o non debba ristrutturare una di quelle antiche case del centro storico di Porto, (dei bellissimi denti completamente cariati dentro), ebbene&#8230;a meno di questi casi particolari, nel momento in cui tu hai bisogno di un progetto d&#8217;architettura, oggi pu\u00f2 essere di moda anche rivolgersi ad imprese &#8220;specialistiche&#8221;. Si tratta di uno scenario assolutamente prevedibile e da me poco conosciuto fino al mese di Febbraio. La gente, forse presa da chiss\u00e0 quali paure, preferisce rivolgersi ad imprese che &#8220;procurano&#8221; progetti d&#8217;architettura. Progetti a &#8220;pronta consegna&#8221;, &#8220;chiavi in mano&#8221; o altri motti mercantili del genere. Non necessariamente queste imprese producono il progetto, anche quando si dotano di architetti nei propri staff (nei famosi &#8220;laboratori&#8221; o &#8220;sezioni creative&#8221;). Infatti queste aziende oltre che ha un portafoglio-clienti ne hanno anche uno -architetti e uno -costruttori dai quali si fanno fornire i progetti e la manovalanza per realizzarli. In un gergo ad altissimo livello di fighetteria, potremmo pensare a queste imprese come a delle &#8220;interfacce&#8221; tra clienti e architetti (e imprese di costruzioni). Di fatto sono dei terzi incomodi che si mettono in mezzo al flusso di denaro che intercorre tra i primi e i secondi cercando di accaparrare qualcosa. Diventano come una specie di dogana tipo alla Non ci resta che piangere. Pi\u00f9 malevolmente potremmo pensarle come a dei &#8220;cabaleros&#8221; del Vecchio West che occupano l&#8217;unico punto esistente nella regione dove si possa guadare il fiume e costringendo le carovane a pagare un pedaggio. Quello che gli architetti pagano \u00e8 il fatto di avere un concorrente in pi\u00f9 nel mondo del mercato, che si pone come una barriera di vetro tra te e il cliente con tutte le conseguenze annesse. <br \/>Gli effetti collaterali sono quelli per cui nel caso subentrino le immancabili &#8220;varianti in corso d&#8217;opera&#8221; molto spesso il cliente scavalca l&#8217;impresa parlando direttamente con l&#8217;architetto. Ne nascono delle vigorose discussioni telefoniche tra le segretarie dell&#8217;impresa e gli architetti stessi, del tipo: &lt;&gt;, o &lt;&gt; fino al &lt;&gt;, e via discorrendo.<br \/>Era molto meglio fare l&#8217;ingegnere, molto meno poetico ma pi\u00f9 pratico e redditizio. Oppure fare l&#8217;ingegniere-artista-inventore, come il buon Leonardo da Vinci, il famoso inventore della locomotiva a <a href=\"http:\/\/www.youtube.com\/watch?v=fg77t0mip6e&amp;hl=it\">vapore<\/a>.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>scrivere <a href=\"https:\/\/blog.professionearchitetto.it\/recibosverdes\/2009\/03\/03\/non-mi-resta-che\/\">[continua]<\/a><\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-47","post","type-post","status-publish","format-standard","hentry","category-senza-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Non mi resta che - Recibos Verdes (Ricevute Verdi)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.professionearchitetto.it\/recibosverdes\/2009\/03\/03\/non-mi-resta-che\/\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ed\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blog.professionearchitetto.it\/recibosverdes\/2009\/03\/03\/non-mi-resta-che\/\",\"url\":\"https:\/\/blog.professionearchitetto.it\/recibosverdes\/2009\/03\/03\/non-mi-resta-che\/\",\"name\":\"Non mi resta che - Recibos Verdes (Ricevute Verdi)\",\"isPartOf\":{\"@id\":\"https:\/\/blog.professionearchitetto.it\/recibosverdes\/#website\"},\"datePublished\":\"2009-03-03T00:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/blog.professionearchitetto.it\/recibosverdes\/#\/schema\/person\/8f1e861fc3230530f1125df775397582\"},\"breadcrumb\":{\"@id\":\"https:\/\/blog.professionearchitetto.it\/recibosverdes\/2009\/03\/03\/non-mi-resta-che\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blog.professionearchitetto.it\/recibosverdes\/2009\/03\/03\/non-mi-resta-che\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.professionearchitetto.it\/recibosverdes\/2009\/03\/03\/non-mi-resta-che\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blog.professionearchitetto.it\/recibosverdes\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Non mi resta che\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.professionearchitetto.it\/recibosverdes\/#website\",\"url\":\"https:\/\/blog.professionearchitetto.it\/recibosverdes\/\",\"name\":\"Recibos Verdes (Ricevute Verdi)\",\"description\":\"i blog di professionearchitetto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.professionearchitetto.it\/recibosverdes\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/blog.professionearchitetto.it\/recibosverdes\/#\/schema\/person\/8f1e861fc3230530f1125df775397582\",\"name\":\"ed\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/blog.professionearchitetto.it\/recibosverdes\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e53627c01b5f15e9699b2d24f274b60a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e53627c01b5f15e9699b2d24f274b60a?s=96&d=mm&r=g\",\"caption\":\"ed\"},\"url\":\"https:\/\/blog.professionearchitetto.it\/recibosverdes\/author\/ed\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Non mi resta che - Recibos Verdes (Ricevute Verdi)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.professionearchitetto.it\/recibosverdes\/2009\/03\/03\/non-mi-resta-che\/","twitter_misc":{"Scritto da":"ed","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blog.professionearchitetto.it\/recibosverdes\/2009\/03\/03\/non-mi-resta-che\/","url":"https:\/\/blog.professionearchitetto.it\/recibosverdes\/2009\/03\/03\/non-mi-resta-che\/","name":"Non mi resta che - Recibos Verdes (Ricevute Verdi)","isPartOf":{"@id":"https:\/\/blog.professionearchitetto.it\/recibosverdes\/#website"},"datePublished":"2009-03-03T00:00:00+00:00","author":{"@id":"https:\/\/blog.professionearchitetto.it\/recibosverdes\/#\/schema\/person\/8f1e861fc3230530f1125df775397582"},"breadcrumb":{"@id":"https:\/\/blog.professionearchitetto.it\/recibosverdes\/2009\/03\/03\/non-mi-resta-che\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.professionearchitetto.it\/recibosverdes\/2009\/03\/03\/non-mi-resta-che\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blog.professionearchitetto.it\/recibosverdes\/2009\/03\/03\/non-mi-resta-che\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.professionearchitetto.it\/recibosverdes\/"},{"@type":"ListItem","position":2,"name":"Non mi resta che"}]},{"@type":"WebSite","@id":"https:\/\/blog.professionearchitetto.it\/recibosverdes\/#website","url":"https:\/\/blog.professionearchitetto.it\/recibosverdes\/","name":"Recibos Verdes (Ricevute Verdi)","description":"i blog di professionearchitetto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.professionearchitetto.it\/recibosverdes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/blog.professionearchitetto.it\/recibosverdes\/#\/schema\/person\/8f1e861fc3230530f1125df775397582","name":"ed","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/blog.professionearchitetto.it\/recibosverdes\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e53627c01b5f15e9699b2d24f274b60a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e53627c01b5f15e9699b2d24f274b60a?s=96&d=mm&r=g","caption":"ed"},"url":"https:\/\/blog.professionearchitetto.it\/recibosverdes\/author\/ed\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.professionearchitetto.it\/recibosverdes\/wp-json\/wp\/v2\/posts\/47","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.professionearchitetto.it\/recibosverdes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.professionearchitetto.it\/recibosverdes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.professionearchitetto.it\/recibosverdes\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.professionearchitetto.it\/recibosverdes\/wp-json\/wp\/v2\/comments?post=47"}],"version-history":[{"count":0,"href":"https:\/\/blog.professionearchitetto.it\/recibosverdes\/wp-json\/wp\/v2\/posts\/47\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.professionearchitetto.it\/recibosverdes\/wp-json\/wp\/v2\/media?parent=47"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.professionearchitetto.it\/recibosverdes\/wp-json\/wp\/v2\/categories?post=47"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.professionearchitetto.it\/recibosverdes\/wp-json\/wp\/v2\/tags?post=47"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}